{"id":282049,"date":"2024-04-10T16:53:54","date_gmt":"2024-04-10T14:53:54","guid":{"rendered":"https:\/\/dimensioneing.it\/?page_id=282049"},"modified":"2026-07-07T12:16:22","modified_gmt":"2026-07-07T10:16:22","slug":"skyway-monte-bianco","status":"publish","type":"page","link":"https:\/\/dimensioneing.it\/en\/skyway-monte-bianco\/","title":{"rendered":"Skyway Mont Blanc"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#057c4c&#8221; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;24vh||8vh||false|false&#8221; custom_padding_tablet=&#8221;27vh||27vh||true|false&#8221; custom_padding_phone=&#8221;12vh||12vh||true|false&#8221; background_last_edited=&#8221;on|phone&#8221; use_background_color_gradient_phone=&#8221;on&#8221; background_color_gradient_stops_phone=&#8221;rgba(0,0,0,0.51) 0%|rgba(0,0,0,0.19) 100%&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Josefin Slab|700||on|||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;20px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; custom_margin=&#8221;||10px||false|false&#8221; header_font_size_tablet=&#8221;17px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>l&#8217;ottava meraviglia del mondo<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;35px&#8221; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;65px&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;40px&#8221; custom_padding=&#8221;||20px||false|false&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;27px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Skyway Monte Bianco<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; width=&#8221;100%&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-55px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; sticky_enabled=&#8221;0&#8243; custom_margin_phone=&#8221;-80px||||false|false&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; custom_margin_tablet=&#8221;-55px||0px||false|false&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; module_class=&#8221;reverse-columns-mobile&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;-100px||||false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;140px|||90px|false|false&#8221; custom_padding_tablet=&#8221;140px|||90px|false|false&#8221; custom_padding_phone=&#8221;0px|||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;|12px||12px|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Definita l'&#8221;ottava Meraviglia del Mondo&#8221;, la SkyWay Monte Bianco \u00e8 stata progettata da Dimensione Ingenierie, che si \u00e8 occupata anche della direzione lavori. L&#8217;impianto funiviario \u00e8 costituito da due segmenti: Pontal d&#8217;Entreves- Pavillon e Pavillon- Punta Herbronner, dove, sull&#8217;iconica Terrazza dei Ghiacciai, \u00e8 possibile godere di una vista spettacolare che abbraccia tutte le Alpi Occidentali.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/skywaymontebianco.jpeg&#8221; title_text=&#8221;skywaymontebianco&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; show_in_lightbox=&#8221;on&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;60px||60px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;0px||10px||false|false&#8221; header_2_font_size_tablet=&#8221;17px&#8221; header_2_font_size_phone=&#8221;15px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>progetto skyway monte bianco<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||60px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Definita l\u2019ottava meraviglia del mondo<\/strong><span>, il nuovo complesso del Monte Bianco \u00e8 sicuramente il nostro progetto pi\u00f9 rilevante che ha coinvolto tecnici e progettisti della nostra struttura per oltre 10 anni di lavoro nel coordinamento generale dei servizi di ingegneria, nella progettazione e nella direzione dei lavori.<\/span><br \/><span>La scelta accurata dei materiali e delle tecnologie ha permesso l\u2019inserimento ambientale delle opere in modo armonico e qualificante per il territorio, garantendo un risultato all\u2019avanguardia sia in termini ingegneristici sia di design.<\/span><br \/><span>La progettazione \u00e8 stata finalizzata per una costruzione \u201ca fianco\u201d degli impianti gi\u00e0 esistenti per consentire l\u2019esercizio turistico dei vecchi impianti, realizzati nel 1947, durante tutta l\u2019esecuzione dei lavori.<\/span><br \/><span>I lavori sono iniziati ad aprile 2011 e il nuovo complesso funiviario \u00e8 entrato in funzione il 30 maggio 2015, dopo soli 4 anni di lavori. Nell\u2019estate 2016 \u00e8 previsto il completamento dei lavori con la demolizione dei vecchi impianti e la trasformazione della vecchia stazione del Pavillon in un\u2019area espositiva e museale.<\/span><br \/><span>Nel nuovo complesso sono attive due funivie su tre siti di stazione: la partenza a Pontal d\u2019Entreves, l\u2019intermedia al Pavillon du Mont Frety e l\u2019arrivo a monte a Punta Helbronner a quota 3466 metri slm.<\/span><br \/><span>Tutto il complesso \u00e8 caratterizzato da elevatissimi standard progettuali al fine di ridurre al minimo il fabbisogno energetico per il riscaldamento\/raffrescamento. Pompe di calore ad alta efficienza, pannelli fotovoltaici, recuperatori di energia e calore consentono al nuovo complesso di non dover ricorrere all\u2019uso di combustibili, con unica obbligata eccezione per i gruppi elettrogeni di emergenza. Parallelamente alla costruzione delle nuove funivie sono stati realizzati un acquedotto e una fognatura a servizio dell\u2019area del Pavillon e un sistema di depurazione completo per la stazione di Punta Helbronner.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/skywaymontebiancoprogetto.jpeg&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;70px|45px|70px|45px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; show_divider=&#8221;off&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; custom_padding=&#8221;50px||50px||true|false&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;80px||80px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;40px|30px|40px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;||10px||false|false&#8221; header_3_font_size_tablet=&#8221;17px&#8221; header_3_font_size_phone=&#8221;15px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Gli impianti a fune<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||60px||false|false&#8221; custom_margin_tablet=&#8221;||60px||false|false&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Gli impianti sono funivie bifuni a \u201cva e vieni\u201d, a doppia fune portante (2 x 64 mm di diametro) con portata oraria di 800 persone\/h per il 1\u00b0 tronco e 600 persone\/h per il 2\u00b0. La velocit\u00e0 di marcia \u00e8 di 9 m\/s senza rallentamenti sui sostegni e pertanto il percorso completo di salita viene coperto in soli 12 minuti. Le cabine possono ospitare 80 persone e sono completamente rotanti e molto vetrate per garantire una visione a 360\u00b0 dei panorami mozzafiato del gruppo del Monte Bianco.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;60px||60px||true|false&#8221; custom_padding_tablet=&#8221;60px||60px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#057c4c&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;off|on|on&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/skyway-progetto.png&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;70px|45px|70px|45px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; title_text=&#8221;skyway progetto&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_divider _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; show_divider=&#8221;off&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; custom_padding=&#8221;50px||50px||true|false&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;80px||80px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;40px|30px|40px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;0px||10px||false|false&#8221; hover_enabled=&#8221;0&#8243; header_3_font_size_tablet=&#8221;17px&#8221; header_3_font_size_phone=&#8221;13px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>La stazione di Valle<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>La stazione trova spazio nell\u2019area libera immediatamente a valle dell\u2019abitato di Entreves ed \u00e8 circoscritta dalla strada Statale 26 di accesso al Traforo del Monte Bianco. Integra numerosi servizi tra cui un parcheggio coperto per circa 300 auto, un parcheggio a raso per 50 autovetture e 10 autobus, biglietteria, locali tecnici e uffici della struttura gestionale, bar, servizi igienici, infermeria e uffici di informazione turistica. La curvatura della copertura fornisce alla stazione un aspetto volutamente aerodinamico capace di adattarsi e saldarsi alla morfologia del terreno naturale. Il rivestimento esterno \u00e8 realizzato in lamiera aggraffata in alluminio-titanio.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; disabled_on=&#8221;on|off|off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/skyway-progetto.png&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; title_text=&#8221;skyway progetto&#8221; force_fullwidth=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; disabled_on=&#8221;on|off|off&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;35px||10px||false|false&#8221; hover_enabled=&#8221;0&#8243; header_3_font_size_tablet=&#8221;17px&#8221; header_3_font_size_phone=&#8221;13px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;on|off|off&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>La stazione di Valle<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||||false|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;on|off|off&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>La stazione trova spazio nell\u2019area libera immediatamente a valle dell\u2019abitato di Entreves ed \u00e8 circoscritta dalla strada Statale 26 di accesso al Traforo del Monte Bianco. Integra numerosi servizi tra cui un parcheggio coperto per circa 300 auto, un parcheggio a raso per 50 autovetture e 10 autobus, biglietteria, locali tecnici e uffici della struttura gestionale, bar, servizi igienici, infermeria e uffici di informazione turistica. La curvatura della copertura fornisce alla stazione un aspetto volutamente aerodinamico capace di adattarsi e saldarsi alla morfologia del terreno naturale. Il rivestimento esterno \u00e8 realizzato in lamiera aggraffata in alluminio-titanio.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;60px||60px||true|false&#8221; custom_padding_tablet=&#8221;60px||60px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#057c4c&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;off|on|on&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/diming-monte-bianco-fascia2-1024&#215;269-1.jpg&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;70px|45px|70px|45px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; title_text=&#8221;diming-monte-bianco-fascia2-1024&#215;269&#8243; sticky_enabled=&#8221;0&#8243;][et_pb_divider _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; show_divider=&#8221;off&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; custom_padding=&#8221;50px||50px||true|false&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;80px||80px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;40px|30px|40px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;0px||10px||false|false&#8221; hover_enabled=&#8221;0&#8243; header_3_font_size_tablet=&#8221;17px&#8221; header_3_font_size_phone=&#8221;15px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>La stazione intermedia<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>La nuova stazione intermedia in localit\u00e0 Pavillon \u00e8 stata pensata in modo da inserirsi elegantemente nell\u2019ondulato contesto alpino del Mont Frety. Le caratteristiche del sito permettono l\u2019inserimento di una serie di servizi complementari come ascensori interni, bar, ristoranti, tutti con terrazza panoramica, una sala convegni multimediale con capacit\u00e0 148 posti, area commerciale, musei, aree di comunicazione tematica, percorsi esterni di avvicinamento alla natura, giardino botanico e solarium esterno, il tutto dominato dalla vista del Monte Bianco.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; disabled_on=&#8221;on|off|off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/diming-monte-bianco-fascia2-1024&#215;269-1.jpg&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; title_text=&#8221;diming-monte-bianco-fascia2-1024&#215;269&#8243; force_fullwidth=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; disabled_on=&#8221;on|off|off&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;35px||10px||false|false&#8221; header_3_font_size_tablet=&#8221;17px&#8221; header_3_font_size_phone=&#8221;15px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>La stazione intermedia<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||||false|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;on|off|off&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span>La nuova stazione intermedia in localit\u00e0 Pavillon \u00e8 stata pensata in modo da inserirsi elegantemente nell\u2019ondulato contesto alpino del Mont Frety. Le caratteristiche del sito permettono l\u2019inserimento di una serie di servizi complementari come ascensori interni, bar, ristoranti, tutti con terrazza panoramica, una sala convegni multimediale con capacit\u00e0 148 posti, area commerciale, musei, aree di comunicazione tematica, percorsi esterni di avvicinamento alla natura, giardino botanico e solarium esterno, il tutto dominato dalla vista del Monte Bianco.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;60px||60px||true|false&#8221; custom_padding_tablet=&#8221;60px||60px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#057c4c&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;off|on|on&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/monte-bianco.jpg&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;70px|45px|70px|45px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; title_text=&#8221;monte-bianco&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_divider _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; show_divider=&#8221;off&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; custom_padding=&#8221;50px||50px||true|false&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;80px||80px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;40px|30px|40px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;35px||10px||false|false&#8221; header_3_font_size_tablet=&#8221;17px&#8221; header_3_font_size_phone=&#8221;15px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>La stazione di monte<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>L\u2019ultima stazione \u00e8 stata realizzata nel rispetto della linea di confine che interseca la vetta a quota 3463 m s.l.m., pertanto i relativi volumi ad essa connessi si sviluppano interamente su territorio italiano. L\u2019intero progetto si sostituisce sui vari versanti alla precedente struttura di cemento: a sud si spinge sul ripido pendio della Punta Helbronner, a nord arriva a posarsi fino allo sperone roccioso immediatamente a valle della stazione francese. La spigolosa natura delle forme esterne \u00e8 in stretta relazione con l\u2019uso di materiali dalle elevate prestazioni. Le forme scelte sono inoltre in grado di limitare l\u2019accumulo di neve e ghiaccio sulle superfici esterne dell\u2019edificio, anche attraverso il contributo delle prestazioni termostatiche dei materiali di rivestimento. L\u2019articolazione degli elementi realizzati con diversi materiali (cemento armato, acciaio, legno e vetro), in base alle differenti funzioni strutturali, fornisce agli spazi interni un originale contenuto ambientale in stretto rapporto con l\u2019esterno. Tutte le aree, interne ed esterne, sono nel cuore del Monte Bianco; una terrazza panoramica di 14 metri di diametro posta sulla copertura della stazione, permette di godere senza ostacoli una vista a 360\u00b0.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/monte-bianco.jpg&#8221; title_text=&#8221;monte-bianco&#8221; show_in_lightbox=&#8221;on&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;on|off|off&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;35px||10px||false|false&#8221; hover_enabled=&#8221;0&#8243; header_3_font_size_tablet=&#8221;17px&#8221; header_3_font_size_phone=&#8221;15px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;on|off|off&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>La stazione di monte<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||||false|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;on|off|off&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span>L\u2019ultima stazione \u00e8 stata realizzata nel rispetto della linea di confine che interseca la vetta a quota 3463 m s.l.m., pertanto i relativi volumi ad essa connessi si sviluppano interamente su territorio italiano. L\u2019intero progetto si sostituisce sui vari versanti alla precedente struttura di cemento: a sud si spinge sul ripido pendio della Punta Helbronner, a nord arriva a posarsi fino allo sperone roccioso immediatamente a valle della stazione francese. La spigolosa natura delle forme esterne \u00e8 in stretta relazione con l\u2019uso di materiali dalle elevate prestazioni. Le forme scelte sono inoltre in grado di limitare l\u2019accumulo di neve e ghiaccio sulle superfici esterne dell\u2019edificio, anche attraverso il contributo delle prestazioni termostatiche dei materiali di rivestimento. L\u2019articolazione degli elementi realizzati con diversi materiali (cemento armato, acciaio, legno e vetro), in base alle differenti funzioni strutturali, fornisce agli spazi interni un originale contenuto ambientale in stretto rapporto con l\u2019esterno. Tutte le aree, interne ed esterne, sono nel cuore del Monte Bianco; una terrazza panoramica di 14 metri di diametro posta sulla copertura della stazione, permette di godere senza ostacoli una vista a 360\u00b0.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||150px||false|false&#8221; custom_padding_tablet=&#8221;||150px||false|false&#8221; custom_padding_phone=&#8221;||70px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_lottie lottie_url=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/C74el9SY6A-1.json&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; transform_rotate=&#8221;0deg|0deg|90deg&#8221; width=&#8221;10%&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; link_option_url=&#8221;https:\/\/dimensioneing.it\/col-checrouit-arp\/&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_lottie][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|||on|||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; link_option_url=&#8221;https:\/\/dimensioneing.it\/col-checrouit-arp\/&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Col Checrouit \u2013 Arp<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_lottie lottie_url=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/C74el9SY6A-1.json&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; transform_rotate=&#8221;0deg|0deg|270deg&#8221; width=&#8221;10%&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; link_option_url=&#8221;https:\/\/dimensioneing.it\/cable-smart-funivia\/&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_lottie][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; text_orientation=&#8221;right&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; link_option_url=&#8221;https:\/\/dimensioneing.it\/cable-smart-funivia\/&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>CABLESMART<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_module=&#8221;282369&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/03\/img2-monte-bianco-scaled-e1641501921709.jpeg&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;150px||150px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; custom_padding=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;80px|50px|80px|50px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#057c4c&#8221; text_font_size=&#8221;19px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; custom_margin=&#8221;||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]CONTATTACI[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|600|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;35px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;1.1em&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;40px&#8221; custom_padding=&#8221;||20px||false|false&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;30px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Ottieni maggiori Informazioni<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||25px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Hai domande o vuoi conoscere meglio la nostra realt\u00e0? Compila il form qui sotto, ti risponderemo al pi\u00f9 presto.<\/p>\n<p>[\/et_pb_text][dsm_contact_form_7 cf7_library=&#8221;12&#8243; input_background_color=&#8221;rgba(147,147,147,0.56)&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; labels_font=&#8221;Montserrat||||||||&#8221; labels_text_color=&#8221;#FFFFFF&#8221; input_textarea_select_text_color=&#8221;#FFFFFF&#8221; placeholder_font=&#8221;Montserrat|600|||||||&#8221; placeholder_text_color=&#8221;#FFFFFF&#8221; custom_button_one=&#8221;on&#8221; button_one_text_size=&#8221;18px&#8221; button_one_text_color=&#8221;#ffffff&#8221; button_one_bg_color=&#8221;#057c4c&#8221; button_one_border_width=&#8221;0px&#8221; button_one_font=&#8221;Montserrat||||||||&#8221; button_one_icon=&#8221;&#x26;||divi||400&#8243; global_colors_info=&#8221;{}&#8221;][\/dsm_contact_form_7][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>l&#8217;ottava meraviglia del mondoSkyway Monte BiancoDefinita l'&#8221;ottava Meraviglia del Mondo&#8221;, la SkyWay Monte Bianco \u00e8 stata progettata da Dimensione Ingenierie, che si \u00e8 occupata anche della direzione lavori. L&#8217;impianto funiviario \u00e8 costituito da due segmenti: Pontal d&#8217;Entreves- Pavillon e Pavillon- Punta Herbronner, dove, sull&#8217;iconica Terrazza dei Ghiacciai, \u00e8 possibile godere di una vista spettacolare che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"difl_page_category":[],"class_list":["post-282049","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Skyway Monte Bianco | DIMENSIONE INGENIERIE S.R.L. FUNICOLARE<\/title>\n<meta name=\"description\" content=\"La SkyWay Monte Bianco \u00e8 stata progettata da Dimensione Ingenierie. Scopri di pi\u00f9 sull\u2019impianto funiviario costituito da due segmenti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dimensioneing.it\/en\/skyway-monte-bianco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skyway Monte Bianco | DIMENSIONE INGENIERIE S.R.L. FUNICOLARE\" \/>\n<meta property=\"og:description\" content=\"La SkyWay Monte Bianco \u00e8 stata progettata da Dimensione Ingenierie. Scopri di pi\u00f9 sull\u2019impianto funiviario costituito da due segmenti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dimensioneing.it\/en\/skyway-monte-bianco\/\" \/>\n<meta property=\"og:site_name\" content=\"DIMENSIONE INGENIERIE S.R.L. FUNICOLARE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T10:16:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dimensioneing.it\/it_it\/skyway-monte-bianco\/\",\"url\":\"https:\/\/dimensioneing.it\/it_it\/skyway-monte-bianco\/\",\"name\":\"Skyway Monte Bianco | DIMENSIONE INGENIERIE S.R.L. FUNICOLARE\",\"isPartOf\":{\"@id\":\"https:\/\/dimensioneing.it\/#website\"},\"datePublished\":\"2024-04-10T14:53:54+00:00\",\"dateModified\":\"2026-07-07T10:16:22+00:00\",\"description\":\"La SkyWay Monte Bianco \u00e8 stata progettata da Dimensione Ingenierie. Scopri di pi\u00f9 sull\u2019impianto funiviario costituito da due segmenti\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dimensioneing.it\/it_it\/skyway-monte-bianco\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dimensioneing.it\/#website\",\"url\":\"https:\/\/dimensioneing.it\/\",\"name\":\"DIMENSIONE INGENIERIE S.R.L. FUNICOLARE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dimensioneing.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Skyway Mont Blanc | DIMENSIONE INGENIERIE S.R.L. FUNICOLARE","description":"SkyWay Mont Blanc was designed by Dimensione Ingenierie. Learn more about the cableway system consisting of two segments","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dimensioneing.it\/en\/skyway-monte-bianco\/","og_locale":"en_US","og_type":"article","og_title":"Skyway Monte Bianco | DIMENSIONE INGENIERIE S.R.L. FUNICOLARE","og_description":"La SkyWay Monte Bianco \u00e8 stata progettata da Dimensione Ingenierie. Scopri di pi\u00f9 sull\u2019impianto funiviario costituito da due segmenti","og_url":"https:\/\/dimensioneing.it\/en\/skyway-monte-bianco\/","og_site_name":"DIMENSIONE INGENIERIE S.R.L. FUNICOLARE","article_modified_time":"2026-07-07T10:16:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dimensioneing.it\/it_it\/skyway-monte-bianco\/","url":"https:\/\/dimensioneing.it\/it_it\/skyway-monte-bianco\/","name":"Skyway Mont Blanc | DIMENSIONE INGENIERIE S.R.L. FUNICOLARE","isPartOf":{"@id":"https:\/\/dimensioneing.it\/#website"},"datePublished":"2024-04-10T14:53:54+00:00","dateModified":"2026-07-07T10:16:22+00:00","description":"SkyWay Mont Blanc was designed by Dimensione Ingenierie. Learn more about the cableway system consisting of two segments","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dimensioneing.it\/it_it\/skyway-monte-bianco\/"]}]},{"@type":"WebSite","@id":"https:\/\/dimensioneing.it\/#website","url":"https:\/\/dimensioneing.it\/","name":"DIMENSION INGENIERIE S.R.L. FUNICULAR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dimensioneing.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dimensioneing.it\/en\/wp-json\/wp\/v2\/pages\/282049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensioneing.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dimensioneing.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dimensioneing.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensioneing.it\/en\/wp-json\/wp\/v2\/comments?post=282049"}],"version-history":[{"count":0,"href":"https:\/\/dimensioneing.it\/en\/wp-json\/wp\/v2\/pages\/282049\/revisions"}],"wp:attachment":[{"href":"https:\/\/dimensioneing.it\/en\/wp-json\/wp\/v2\/media?parent=282049"}],"wp:term":[{"taxonomy":"difl_page_category","embeddable":true,"href":"https:\/\/dimensioneing.it\/en\/wp-json\/wp\/v2\/difl_page_category?post=282049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}