{"id":282177,"date":"2024-04-11T11:15:08","date_gmt":"2024-04-11T09:15:08","guid":{"rendered":"https:\/\/dimensioneing.it\/?page_id=282177"},"modified":"2026-07-07T12:37:15","modified_gmt":"2026-07-07T10:37:15","slug":"genova-gate","status":"publish","type":"page","link":"https:\/\/dimensioneing.it\/it_it\/genova-gate\/","title":{"rendered":"Genova \u2013 Gate"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#057c4c&#8221; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;24vh||8vh||false|false&#8221; custom_padding_tablet=&#8221;27vh||27vh||true|false&#8221; custom_padding_phone=&#8221;12vh||12vh||true|false&#8221; background_last_edited=&#8221;on|phone&#8221; use_background_color_gradient_phone=&#8221;on&#8221; background_color_gradient_stops_phone=&#8221;rgba(0,0,0,0.51) 0%|rgba(0,0,0,0.19) 100%&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Josefin Slab|700||on|||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;20px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; custom_margin=&#8221;||10px||false|false&#8221; header_font_size_tablet=&#8221;17px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>nuova stazione ferroviaria<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;35px&#8221; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;65px&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;40px&#8221; custom_padding=&#8221;||20px||false|false&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;27px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Genova \u2013 Gate<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; width=&#8221;100%&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-55px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; module_class=&#8221;reverse-columns-mobile&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;-100px||||false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;140px|||90px|false|false&#8221; custom_padding_tablet=&#8221;140px|||90px|false|false&#8221; custom_padding_phone=&#8221;0px|||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;|12px||12px|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Progettazione della nuova stazione ferroviaria Erzelli\/Aeroporto della linea Genova-Ventimiglia, e collegamento tramite sistema ibrido fune- automotore RopeTaxi per il collegamento tra la stazione feroviaria e il terminal passeggeri aeroportuale. La completa fermata dei veicoli in stazione, resa tecnicamente possibile dall&#8217;innovativo sistema RopeTaxi, garantisce la piena fruizione del sistema e il comodo imbarco e sbarco anche da parte di passeri con bagagli, passeggini.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/diming-genova-cuore.png&#8221; title_text=&#8221;diming-genova-cuore&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;60px||60px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; header_3_font=&#8221;Josefin Slab|700||on|||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#057c4c&#8221; header_3_font_size=&#8221;17px&#8221; custom_margin=&#8221;0px||10px||false|false&#8221; header_2_font_size_tablet=&#8221;17px&#8221; header_2_font_size_phone=&#8221;15px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>progetto gate<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||60px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Il progetto GATE \u00e8 costituito da due distinti sotto-progetti:<\/p>\n<ul>\n<li>la nuova fermata ferroviaria di Erzelli\/Aeroporto, collocata sulla linea Genova-Ventimiglia, tra le stazioni di Sestri Ponente e Cornigliano<\/li>\n<li>l\u2019impianto di collegamento a fune tra la nuova fermata e il terminal passeggeri aeroportuale.<\/li>\n<\/ul>\n<p>La soluzione adottata per l\u2019impianto di collegamento \u00e8 quella di una cabinovia a grappolo va e vieni con veicoli da 10 posti, avente portata compresa tra le 600 e le 700 persone all\u2019ora. L\u2019impianto prevede la fermata delle cabine in stazione, per consentire un facile accesso ed esodo, anche da parte di passeggeri a mobilit\u00e0 ridotta.<br \/>In virt\u00f9 delle esigenze di trasporto, si prevede che l\u2019impianto possa operare per oltre 5.000 ore \/ anno<br \/>La soluzione tecnologica adottata garantisce bassi costi di esercizio e di manutenzione.<br \/>Il progetto si inserisce in un quadro di investimenti infrastrutturali pi\u00f9 ampio che comprende l\u2019ammodernamento dell\u2019aerostazione e la creazione del futuro polo intermodale aeroportuale (progetto GATE 2), ed in futuro anche il collegamento con l\u2019area insediativa degli Erzelli.<br \/>Gli edifici di stazione sono concepiti per integrarsi al meglio con il terminal aeroportuale preesistente e con la nuova stazione ferroviaria.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;off|off|off&#8221; sticky_enabled=&#8221;0&#8243; title_text=&#8221;diming-genova-banner-1024&#215;269&#8243; background_image=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/04\/diming-genova-banner-1024&#215;269-1.jpg&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|true&#8221; custom_padding_tablet=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_phone=&#8221;20px|30px|20px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; show_divider=&#8221;off&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; custom_padding=&#8221;200px||200px||true|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_padding_phone=&#8221;100px||100px||true|false&#8221; custom_padding_tablet=&#8221;200px||200px||true|false&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_module=&#8221;282369&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/dimensioneing.it\/wp-content\/uploads\/2024\/03\/img2-monte-bianco-scaled-e1641501921709.jpeg&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;150px||150px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; custom_padding=&#8221;130px|100px|130px|100px|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;80px|50px|80px|50px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Josefin Slab|600|||||||&#8221; text_text_color=&#8221;#057c4c&#8221; text_font_size=&#8221;19px&#8221; text_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Josefin Slab|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#057c4c&#8221; header_2_font_size=&#8221;17px&#8221; custom_margin=&#8221;||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]CONTATTACI[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|600|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;35px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;1.1em&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;40px&#8221; custom_padding=&#8221;||20px||false|false&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;30px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Ottieni maggiori Informazioni<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_letter_spacing=&#8221;1px&#8221; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; custom_margin=&#8221;||25px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Hai domande o vuoi conoscere meglio la nostra realt\u00e0? Compila il form qui sotto, ti risponderemo al pi\u00f9 presto.<\/p>\n<p>[\/et_pb_text][dsm_contact_form_7 cf7_library=&#8221;12&#8243; input_background_color=&#8221;rgba(147,147,147,0.56)&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; labels_font=&#8221;Montserrat||||||||&#8221; labels_text_color=&#8221;#FFFFFF&#8221; input_textarea_select_text_color=&#8221;#FFFFFF&#8221; placeholder_font=&#8221;Montserrat|600|||||||&#8221; placeholder_text_color=&#8221;#FFFFFF&#8221; custom_button_one=&#8221;on&#8221; button_one_text_size=&#8221;18px&#8221; button_one_text_color=&#8221;#ffffff&#8221; button_one_bg_color=&#8221;#057c4c&#8221; button_one_border_width=&#8221;0px&#8221; button_one_font=&#8221;Montserrat||||||||&#8221; button_one_icon=&#8221;&#x26;||divi||400&#8243; global_colors_info=&#8221;{}&#8221;][\/dsm_contact_form_7][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>nuova stazione ferroviariaGenova \u2013 GateProgettazione della nuova stazione ferroviaria Erzelli\/Aeroporto della linea Genova-Ventimiglia, e collegamento tramite sistema ibrido fune- automotore RopeTaxi per il collegamento tra la stazione feroviaria e il terminal passeggeri aeroportuale. La completa fermata dei veicoli in stazione, resa tecnicamente possibile dall&#8217;innovativo sistema RopeTaxi, garantisce la piena fruizione del sistema e il comodo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"difl_page_category":[],"class_list":["post-282177","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuova stazione ferroviaria Genova \u2013 Gate DIMENSIONE INGENIERIE S.R.L. FUNICOLARE |<\/title>\n<meta name=\"description\" content=\"Scopri il progetto della stazione ferroviaria Erzelli\/Aeroporto della linea Genova-Ventimiglia con collegamento tramite sistema ibrido fune- automotore\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dimensioneing.it\/it_it\/genova-gate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuova stazione ferroviaria Genova \u2013 Gate DIMENSIONE INGENIERIE S.R.L. FUNICOLARE |\" \/>\n<meta property=\"og:description\" content=\"Scopri il progetto della stazione ferroviaria Erzelli\/Aeroporto della linea Genova-Ventimiglia con collegamento tramite sistema ibrido fune- automotore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dimensioneing.it\/it_it\/genova-gate\/\" \/>\n<meta property=\"og:site_name\" content=\"DIMENSIONE INGENIERIE S.R.L. FUNICOLARE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T10:37:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dimensioneing.it\/it_it\/genova-gate\/\",\"url\":\"https:\/\/dimensioneing.it\/it_it\/genova-gate\/\",\"name\":\"Nuova stazione ferroviaria Genova \u2013 Gate DIMENSIONE INGENIERIE S.R.L. FUNICOLARE |\",\"isPartOf\":{\"@id\":\"https:\/\/dimensioneing.it\/#website\"},\"datePublished\":\"2024-04-11T09:15:08+00:00\",\"dateModified\":\"2026-07-07T10:37:15+00:00\",\"description\":\"Scopri il progetto della stazione ferroviaria Erzelli\/Aeroporto della linea Genova-Ventimiglia con collegamento tramite sistema ibrido fune- automotore\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dimensioneing.it\/it_it\/genova-gate\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dimensioneing.it\/#website\",\"url\":\"https:\/\/dimensioneing.it\/\",\"name\":\"DIMENSIONE INGENIERIE S.R.L. FUNICOLARE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dimensioneing.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuova stazione ferroviaria Genova \u2013 Gate DIMENSIONE INGENIERIE S.R.L. FUNICOLARE |","description":"Scopri il progetto della stazione ferroviaria Erzelli\/Aeroporto della linea Genova-Ventimiglia con collegamento tramite sistema ibrido fune- automotore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dimensioneing.it\/it_it\/genova-gate\/","og_locale":"it_IT","og_type":"article","og_title":"Nuova stazione ferroviaria Genova \u2013 Gate DIMENSIONE INGENIERIE S.R.L. FUNICOLARE |","og_description":"Scopri il progetto della stazione ferroviaria Erzelli\/Aeroporto della linea Genova-Ventimiglia con collegamento tramite sistema ibrido fune- automotore","og_url":"https:\/\/dimensioneing.it\/it_it\/genova-gate\/","og_site_name":"DIMENSIONE INGENIERIE S.R.L. FUNICOLARE","article_modified_time":"2026-07-07T10:37:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dimensioneing.it\/it_it\/genova-gate\/","url":"https:\/\/dimensioneing.it\/it_it\/genova-gate\/","name":"Nuova stazione ferroviaria Genova \u2013 Gate DIMENSIONE INGENIERIE S.R.L. FUNICOLARE |","isPartOf":{"@id":"https:\/\/dimensioneing.it\/#website"},"datePublished":"2024-04-11T09:15:08+00:00","dateModified":"2026-07-07T10:37:15+00:00","description":"Scopri il progetto della stazione ferroviaria Erzelli\/Aeroporto della linea Genova-Ventimiglia con collegamento tramite sistema ibrido fune- automotore","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dimensioneing.it\/it_it\/genova-gate\/"]}]},{"@type":"WebSite","@id":"https:\/\/dimensioneing.it\/#website","url":"https:\/\/dimensioneing.it\/","name":"DIMENSIONE INGENIERIE S.R.L. FUNICOLARE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dimensioneing.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/dimensioneing.it\/it_it\/wp-json\/wp\/v2\/pages\/282177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensioneing.it\/it_it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dimensioneing.it\/it_it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dimensioneing.it\/it_it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensioneing.it\/it_it\/wp-json\/wp\/v2\/comments?post=282177"}],"version-history":[{"count":0,"href":"https:\/\/dimensioneing.it\/it_it\/wp-json\/wp\/v2\/pages\/282177\/revisions"}],"wp:attachment":[{"href":"https:\/\/dimensioneing.it\/it_it\/wp-json\/wp\/v2\/media?parent=282177"}],"wp:term":[{"taxonomy":"difl_page_category","embeddable":true,"href":"https:\/\/dimensioneing.it\/it_it\/wp-json\/wp\/v2\/difl_page_category?post=282177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}